{"id":6224,"date":"2026-05-04T14:01:53","date_gmt":"2026-05-04T17:01:53","guid":{"rendered":"https:\/\/cdsalta.gob.ar\/?p=6224"},"modified":"2026-05-04T14:01:53","modified_gmt":"2026-05-04T17:01:53","slug":"empleados-del-concejo-deliberante-celebraron-el-dia-del-trabajador-con-un-almuerzo","status":"publish","type":"post","link":"https:\/\/cdsalta.gob.ar\/index.php\/2026\/05\/04\/empleados-del-concejo-deliberante-celebraron-el-dia-del-trabajador-con-un-almuerzo\/","title":{"rendered":"<span style='font-size:16px;font-weight:normal;'>El agasajo fue organizado por el SECoDe<\/span> <br> <span style='font-size:20px;font-weight:bold;'>Empleados del Concejo Deliberante celebraron el D\u00eda del Trabajador con un almuerzo<\/span>"},"content":{"rendered":"<p style=\"text-align: justify\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6234\" src=\"https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg\" alt=\"\" width=\"799\" height=\"450\" srcset=\"https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg 799w, https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c-300x169.jpg 300w, https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c-768x433.jpg 768w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>El pasado jueves al mediod\u00eda, los empleados del CD compartieron un almuerzo junto a las autoridades del Cuerpo legislativo y ediles de diferentes bancadas en el marco del D\u00eda del Trabajador. El agasajo se realiz\u00f3 en las instalaciones del sal\u00f3n de eventos Nova Vila y fue organizado por el Sindicato de Empleados del Concejo Deliberante (SECoDe).<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>En la celebraci\u00f3n, el presidente del CD, Dar\u00edo Madile, dirigi\u00f3 unas palabras a los trabajadores, resaltando la labor que realizan diariamente: \u201cEs un buen momento para agradecer que tenemos trabajo y reflexionar sobre la importancia de hacer cada d\u00eda mejor nuestra tarea\u201d. A lo que agreg\u00f3: \u201cCreo que, si bien son tiempos dif\u00edciles, tener la oportunidad de compartir fuera de lo que es el \u00e1mbito laboral siempre es muy bueno. Por eso tambi\u00e9n quiero agradecer el esfuerzo del Sindicato que viene trabajando hace tiempo para que esto sea posible\u201d.\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify\">El espacio permiti\u00f3 a los trabajadores dejar de lado por un momento las tareas habituales y celebrar su d\u00eda junto a compa\u00f1eros de todas las oficinas.<\/p>\n<p style=\"text-align: justify\">Durante el desarrollo del agasajo tambi\u00e9n tom\u00f3 la palabra el <strong>secretario General del S.E.Co.De, Luis Rodr\u00edguez<\/strong>, quien se dirigi\u00f3 a los presentes sosteniendo: <strong>\u201cEl Sindicato somos todos, nosotros administramos, pero esta celebraci\u00f3n es de ustedes para ustedes\u201d<\/strong>. Adem\u00e1s, a\u00f1adi\u00f3: \u201cQuiero agradecerles a todos porque d\u00eda a d\u00eda hacen crecer al Concejo Deliberante\u201d. Finalmente, <strong>resalt\u00f3 la importancia de cuidar la instituci\u00f3n<\/strong>: \u201cDurante este tiempo hemos visto pasar muchos Cuerpos legislativos y siempre hemos trabajado para todos, sin distinci\u00f3n de banderas pol\u00edticas, porque nosotros trabajamos para el Concejo\u201d.<\/p>\n<p style=\"text-align: justify\">En el evento estuvieron presentes los ediles Malvina Gareca (PC), Eliana Chuchuy, Alicia Vargas, Gustavo Farquharson (todos de PS), Laura Garc\u00eda (VS), \u00c1ngel Ortiz (UCR) y Gonzalo Nieva (J).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado jueves al mediod\u00eda, los empleados del CD compartieron un almuerzo junto a las autoridades del Cuerpo legislativo y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"uagb_featured_image_src":{"full":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg",799,450,false],"thumbnail":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c-150x150.jpg",150,150,true],"medium":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c-300x169.jpg",300,169,true],"medium_large":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c-768x433.jpg",768,433,true],"large":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg",799,450,false],"1536x1536":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg",799,450,false],"2048x2048":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg",799,450,false],"mailpoet_newsletter_max":["https:\/\/cdsalta.gob.ar\/wp-content\/uploads\/2026\/05\/55248464094_d7b5447354_c.jpg",799,450,false]},"uagb_author_info":{"display_name":"Prensa","author_link":"https:\/\/cdsalta.gob.ar\/index.php\/author\/prensa\/"},"uagb_comment_info":0,"uagb_excerpt":"El pasado jueves al mediod\u00eda, los empleados del CD compartieron un almuerzo junto a las autoridades del Cuerpo legislativo y [&hellip;]","_links":{"self":[{"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6224"}],"version-history":[{"count":1,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6224\/revisions"}],"predecessor-version":[{"id":6236,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6224\/revisions\/6236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/6234"}],"wp:attachment":[{"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdsalta.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}